{"id":6350,"date":"2009-08-25T10:02:56","date_gmt":"2009-08-25T10:02:56","guid":{"rendered":"https:\/\/pontiacarchives.org.ottawavalleymedia.ca\/nouveaux-livres-recensements-et-registres-paroissiaux\/"},"modified":"2009-08-25T10:02:56","modified_gmt":"2009-08-25T10:02:56","slug":"nouveaux-livres-recensements-et-registres-paroissiaux","status":"publish","type":"post","link":"https:\/\/pontiacarchives.org\/fr\/nouveaux-livres-recensements-et-registres-paroissiaux\/","title":{"rendered":"Nouveaux livres, recensements et registres paroissiaux"},"content":{"rendered":"<p style=\"text-align: left;\">Les Archives du Pontiac ont re\u00e7u en don les livres suivants. Ils sont \u00e0 la disposition des visiteurs pour qu&rsquo;ils les lisent et les appr\u00e9cient, mais ils ne doivent pas sortir des locaux.<\/p>\n<p style=\"text-align: left;\"><em>Soixante-dix ans de souvenirs<\/em>, par Doris Barber Orr<\/p>\n<p style=\"text-align: left;\"><em>Les p\u00e2turages verts<\/em>, par Laura May Harris<\/p>\n<p style=\"text-align: left;\"><em>J&rsquo;ai toujours voulu faire plaisir \u00e0 ma m\u00e8re<\/em>, par Lynette Harris<\/p>\n<p style=\"text-align: left;\"><em>Leur terre de promesse<\/em>, par Laura May Harris<\/p>\n<p style=\"text-align: left;\"><strong>Les recensements sur microfilm <\/strong>1842 &#8211; 1901 et les <strong>registres paroissiaux sur microfilm\u00c2<\/strong>de Quyon &amp; North Onslow ; Fort Coulonge ; Vinton ; Ile du Grand Calumet ; East Alfield ; Demers Centre ; Campbell&rsquo;s Bay ; Otter Lake ; Temiscaming Ville Marie ; Nord de l&rsquo;Ontario ; Rouyn ; Bryson ; Litchfield ; Noranda ; Sheen ; Bristol ; Maryland ; Lac Cayamant ; Portage du Fort ; St Joseph ; Fort William ; La Passe ; Eganville ; Golden Lake ; Pembroke, etc. sont disponibles pour les chercheurs sur un lecteur de microfilms r\u00e9cemment acquis \u00e0 titre de don.<\/p>\n<p style=\"text-align: left;\">\u00c2  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Archives du Pontiac ont re\u00e7u en don les livres suivants. Ils sont \u00e0 la disposition des visiteurs pour qu&rsquo;ils les lisent et les appr\u00e9cient, mais ils ne doivent pas sortir des locaux. Soixante-dix ans de souvenirs, par Doris Barber Orr Les p\u00e2turages verts, par Laura May Harris J&rsquo;ai toujours voulu faire plaisir \u00e0 ma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[89],"tags":[],"class_list":["post-6350","post","type-post","status-publish","format-standard","hentry","category-annonces"],"acf":[],"_links":{"self":[{"href":"https:\/\/pontiacarchives.org\/fr\/wp-json\/wp\/v2\/posts\/6350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pontiacarchives.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pontiacarchives.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pontiacarchives.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pontiacarchives.org\/fr\/wp-json\/wp\/v2\/comments?post=6350"}],"version-history":[{"count":0,"href":"https:\/\/pontiacarchives.org\/fr\/wp-json\/wp\/v2\/posts\/6350\/revisions"}],"wp:attachment":[{"href":"https:\/\/pontiacarchives.org\/fr\/wp-json\/wp\/v2\/media?parent=6350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pontiacarchives.org\/fr\/wp-json\/wp\/v2\/categories?post=6350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pontiacarchives.org\/fr\/wp-json\/wp\/v2\/tags?post=6350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}